{"id":38,"date":"2024-06-17T04:14:22","date_gmt":"2024-06-17T04:14:22","guid":{"rendered":"https:\/\/www.ppd.com\/fr\/?page_id=38"},"modified":"2025-01-28T23:56:10","modified_gmt":"2025-01-28T23:56:10","slug":"clinical-data-management","status":"publish","type":"page","link":"https:\/\/www.ppd.com\/fr\/functional-service-providers\/clinical-data-management\/","title":{"rendered":"Gestion des donn\u00e9es cliniques PSF"},"content":{"rendered":"\n<div class=\"wp-block-emagine-columns alignfull\" id=\"page-intro\"><div id=\"em-layout-id_page-intro\" class=\"em-row-layout-inner em-margin-top--default em-margin-bottom--none em-tablet-margin-top--default em-tablet-margin-bottom--none em-mobile-margin-top--default em-mobile-margin-bottom--none   em-layout-id_page-intro\"><div class=\"em-row-column-wrap em-has-2-columns em-gutter-default em-row-valign-top em-row-layout-left-golden em-tab-layout-left-golden em-m-colapse-left-to-right em-mobile-layout-row em-padding-top--default em-padding-bottom--default em-tablet-padding-top--default em-tablet-padding-bottom--default em-mobile-padding-top--default em-mobile-padding-bottom--default alignwide\">\n<div class=\"wp-block-emagine-column emagine-column5150 inner-column-1\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--medium em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--medium em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--medium em-mobile-padding-left--none\">\n<h2 class=\"wp-block-heading\">Les solutions dont vous avez besoin pour prendre des d\u00e9cisions plus rapides et plus intelligentes et pour respecter vos \u00e9ch\u00e9ances<\/h2>\n\n\n\n<p>Alors que le volume de donn\u00e9es recueillies dans le cadre des essais cliniques ne cesse d\u2019augmenter et que l\u2019industrie s\u2019oriente vers des conceptions d\u2019essais plus complexes et des approches ax\u00e9es sur le patient, il est essentiel de consolider, de valider et d\u2019examiner efficacement les sources de donn\u00e9es disparates avec rapidit\u00e9 et transparence.&nbsp;<\/p>\n\n\n\n<p>Les solutions de gestion des donn\u00e9es cliniques des\u202fPSF de\u202fPPD\u2122 aident les organisations biopharmaceutiques et de biotechnologie, ainsi que les fabricants de dispositifs m\u00e9dicaux \u00e0 pr\u00e9server l\u2019int\u00e9grit\u00e9 de leurs donn\u00e9es d\u2019essais cliniques en leur offrant des solutions compl\u00e8tes en gestion des donn\u00e9es cliniques\u202f(GDC) offrant la souplesse, la fiabilit\u00e9 et la continuit\u00e9 des ressources dont ils ont tant besoin.&nbsp;<\/p>\n\n\n\n<p>Reposant sur plus de 25\u202fans d\u2019exp\u00e9rience, nos solutions de\u202fGDC de bout en bout et nos mod\u00e8les de livraison souples fournissent la technologie, les processus et l\u2019expertise n\u00e9cessaires pour rapidement obtenir des donn\u00e9es de qualit\u00e9 permettant aux \u00e9quipes d\u2019\u00e9tude de prendre des d\u00e9cisions plus rapidement et plus intelligemment, ainsi que de respecter les jalons critiques.&nbsp;<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-emagine-column emagine-column3525 inner-column-2\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--none em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--none em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\">\n<figure class=\"wp-block-image size-full hide-on-mobile\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"496\" src=\"https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/digital-trial-hexagon-5ea2ecf07bb3a.jpg\" alt=\"digital-trial-hexagon\" class=\"wp-image-1250\" srcset=\"https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/digital-trial-hexagon-5ea2ecf07bb3a.jpg 400w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/digital-trial-hexagon-5ea2ecf07bb3a-242x300.jpg 242w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/digital-trial-hexagon-5ea2ecf07bb3a-40x50.jpg 40w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<section id=\"media-content-block_2d0608efcbb0ac14c65a81b28ff5af4b\" class=\"media-content alignfull has-bg-image thirds-layout invert-mobile align-content-center \">\n\t\n\t\t\t\t\t\t<div class=\"alignwide align-bg\">\n\t\t\n\t\t\t\t\t<div class=\"media-content__content has-container left-content\">\n\t\t\t\t<div class=\"content-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"media-content__title2\">Les solutions de gestion des donn\u00e9es cliniques de bout en bout pr\u00e9servent l\u2019int\u00e9grit\u00e9 des donn\u00e9es <\/h2>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"media-content__desc\"><p><span class=\"TextRun SCXW130670533 BCX0\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW130670533 BCX0\">Pour pr\u00e9server l\u2019int\u00e9grit\u00e9 des donn\u00e9es et mieux outiller les \u00e9quipes d\u2019\u00e9tude, nous offrons la technologie, les processus et l\u2019expertise n\u00e9cessaires pour obtenir des donn\u00e9es de qualit\u00e9 dans un large \u00e9ventail de domaines th\u00e9rapeutiques, des technologies de saisie \u00e9lectronique des <\/span><span class=\"NormalTextRun SCXW130670533 BCX0\">donn\u00e9es\u202f(SED), des fournisseurs tiers, des services d\u2019essais cliniques de phases\u202fI \u00e0 IV et des strat\u00e9gies avanc\u00e9es de nettoyage des donn\u00e9es dans le cadre de nos solutions de\u202fGDC de bout en bout.<\/span><\/span><span class=\"EOP SCXW130670533 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span class=\"TextRun SCXW164122243 BCX0\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW164122243 BCX0\">Nos gestionnaires de donn\u00e9es sont plus que des technologues; ce sont des intendants des donn\u00e9es, qui travaillent \u00e0 la collecte et \u00e0 la gestion de donn\u00e9es en temps r\u00e9el, ainsi qu\u2019\u00e0 la consolidation de sources de donn\u00e9es disparates. En combinant les donn\u00e9es d\u2019essais cliniques provenant d\u2019une seule \u00e9tude ou d\u2019un ensemble d\u2019\u00e9tudes, au niveau du compos\u00e9 ou d\u2019une gamme de produits, ou encore des donn\u00e9es provenant de fournisseurs externes, nous am\u00e9liorons consid\u00e9rablement la transparence des donn\u00e9es et la qualit\u00e9 de la prise de d\u00e9cision.<\/span><\/span><span class=\"EOP SCXW164122243 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"media-content__image bg-image\">\n\t\t\t\t\t\t\t<div class=\"em-bg-image\">\n\t\t\t\t\t<img src='https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/Evidera-Diversity-RWD-Blog-AdobeStock_321008332.jpg' width='1200' height='675' srcset='https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/Evidera-Diversity-RWD-Blog-AdobeStock_321008332.jpg 1200w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/Evidera-Diversity-RWD-Blog-AdobeStock_321008332-300x169.jpg 300w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/Evidera-Diversity-RWD-Blog-AdobeStock_321008332-1024x576.jpg 1024w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/Evidera-Diversity-RWD-Blog-AdobeStock_321008332-768x432.jpg 768w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/Evidera-Diversity-RWD-Blog-AdobeStock_321008332-60x34.jpg 60w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/Evidera-Diversity-RWD-Blog-AdobeStock_321008332-995x560.jpg 995w' alt='' \/>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\t<\/section>\n\n\n\n<div class=\"wp-block-emagine-columns alignfull\" id=\"life-cycle\"><div id=\"em-layout-id_life-cycle\" class=\"em-row-layout-inner em-margin-top--none em-margin-bottom--none em-tablet-margin-top--none em-tablet-margin-bottom--none em-mobile-margin-top--none em-mobile-margin-bottom--none em-row-has-bg  em-layout-id_life-cycle\"><div class=\"em-row-layout-overlay em-row-overlay-normal\"><\/div><div class=\"em-row-column-wrap em-has-1-columns em-gutter-default em-row-valign-top em-row-layout-equal em-tab-layout-inherit em-m-colapse-left-to-right em-mobile-layout-row em-padding-top--xlarge em-padding-bottom--default em-tablet-padding-top--default em-tablet-padding-bottom--default em-mobile-padding-top--none em-mobile-padding-bottom--default alignwide\">\n<div class=\"wp-block-emagine-column emagine-column3190 inner-column-1\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--none em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--none em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\">\n<h3 class=\"wp-block-heading has-text-align-left h2-large\" style=\"text-transform:none\">Des solutions compl\u00e8tes qui englobent l\u2019ensemble du cycle de vie des donn\u00e9es\u00a0<\/h3>\n\n\n\n<div class=\"wp-block-emagine-columns alignfull\"><div id=\"em-layout-id_7b895c-50\" class=\"em-row-layout-inner em-margin-top--none em-margin-bottom--none em-tablet-margin-top--none em-tablet-margin-bottom--none em-mobile-margin-top--none em-mobile-margin-bottom--none   em-layout-id_7b895c-50\"><div class=\"em-row-column-wrap em-has-3-columns em-gutter-default em-row-valign-top em-row-layout-equal em-tab-layout-inherit em-m-colapse-left-to-right em-mobile-layout-row em-padding-top--xlarge em-padding-bottom--default em-tablet-padding-top--default em-tablet-padding-bottom--default em-mobile-padding-top--default em-mobile-padding-bottom--default alignwide\">\n<div class=\"wp-block-emagine-column emagine-column7820 inner-column-1\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--none em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--none em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\"><div id=\"ppd-card-block_e04041e73e710848cd0e5f363ae19109\" class=\"ppd-card alignfull    no-bottom-card has-hex   \">\n\n\t\t<div class=\"ppd-card__hexagon\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/icon-expert.png\" alt=\"\">\n\t<\/div>\n\t\n\t\n\t<div class=\"ppd-card__inner pad-btm\">\n\t\t<div class=\"ppd-card__top\">\n\t\t\t\t<div class=\"ppd-card__title\">Strat\u00e9gie et configuration <\/div>\n\t\t\t\t<p class=\"ppd-card__content\"><ul class=\"ppd-card__content\"><li> Conseils en mati\u00e8re de strat\u00e9gie relative aux donn\u00e9es <\/li><li> Base de donn\u00e9es\u202f: conception, \u00e9tablissement et tests <\/li><li> Conception du cahier d\u2019observations \u00e9lectronique\u202f(eCRF) <\/li><li>Cartographie et consolidation du mod\u00e8le de tabulation des donn\u00e9es d\u2019\u00e9tude\u202f(SDTM, study data tabulation model) du\u202fCDISC (Clinical Data Interchange Standards Consortium) <\/li><ul><\/p>\n\t\t<\/div>\n\t<div class=\"ppd-card__bottom\">\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-emagine-column emagine-column432 inner-column-2\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--none em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--none em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\"><div id=\"ppd-card-block_d96d340efb8175111e12831cd9ed5457\" class=\"ppd-card alignfull    no-bottom-card has-hex   \">\n\n\t\t<div class=\"ppd-card__hexagon\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/icon-rules.svg\" alt=\"\">\n\t<\/div>\n\t\n\t\n\t<div class=\"ppd-card__inner pad-btm\">\n\t\t<div class=\"ppd-card__top\">\n\t\t\t\t<div class=\"ppd-card__title\">Ex\u00e9cution <\/div>\n\t\t\t\t<p class=\"ppd-card__content\"><ul class=\"ppd-card__content\"><li>Gestion de projets <\/li><li>Codage m\u00e9dical <\/li><li>Validation des donn\u00e9es et r\u00e9solution des demandes d\u2019information <\/li><li>Int\u00e9gration des donn\u00e9es provenant des sources suivantes\u202f: \u00e9valuation \u00e9lectronique des r\u00e9sultats cliniques, technologie de r\u00e9ponse interactive, consentement \u00e9lectronique, donn\u00e9es de laboratoire, r\u00e9sultats d\u00e9clar\u00e9s par les cliniciens ou les dispositifs \u00e9lectroniques, diverses sources \u00e9lectroniques, dispositifs portables (p.\u202fex. applications, montres, moniteurs, timbres), etc. <li>Gestion et rapprochement des donn\u00e9es de tiers <\/li><li>Gestion des donn\u00e9es des laboratoires locaux <\/li><ul><\/p>\n\t\t<\/div>\n\t<div class=\"ppd-card__bottom\">\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-emagine-column emagine-column3556 inner-column-3\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--none em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--none em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\"><div id=\"ppd-card-block_e12d0f6c9697b311db05a44ed842a681\" class=\"ppd-card alignfull    no-bottom-card has-hex   \">\n\n\t\t<div class=\"ppd-card__hexagon\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/icon-cog-1.svg\" alt=\"\">\n\t<\/div>\n\t\n\t\n\t<div class=\"ppd-card__inner pad-btm\">\n\t\t<div class=\"ppd-card__top\">\n\t\t\t\t<div class=\"ppd-card__title\">Technologie <\/div>\n\t\t\t\t<p class=\"ppd-card__content\"><ul class=\"ppd-card__content\"><li>Expertise en mati\u00e8re de d\u00e9ploiement, de validation, de tests et de formation relativement aux syst\u00e8mes de\u202fSED les plus utilis\u00e9s <\/li><li>Assurer la formation \u00e0 la gestion des donn\u00e9es cliniques et \u00e0 des aspects techniques, au niveau de l\u2019\u00e9quipe et du centre <\/li><li>Preclarus, notre plateforme exclusive de donn\u00e9es et d\u2019analyse, offre un acc\u00e8s en temps r\u00e9el aux donn\u00e9es d\u2019\u00e9tude et de laboratoire par l\u2019interm\u00e9diaire de tableaux de bord permettant de voir des donn\u00e9es et des rapports interactifs <\/li><ul><\/p>\n\t\t<\/div>\n\t<div class=\"ppd-card__bottom\">\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<section id=\"bg-content-block-block_fcce4f64d754625f3756c349e3ee1d19\" class=\"bg-content-block alignfull\">\n\t\t\t<div class=\"em-bg-image\">\n\t\t\t<img src='https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/access-solutions-video-conference_1818069584_parallax.jpg' width='1600' height='800' srcset='https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/access-solutions-video-conference_1818069584_parallax.jpg 1600w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/access-solutions-video-conference_1818069584_parallax-300x150.jpg 300w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/access-solutions-video-conference_1818069584_parallax-1024x512.jpg 1024w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/access-solutions-video-conference_1818069584_parallax-768x384.jpg 768w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/access-solutions-video-conference_1818069584_parallax-1536x768.jpg 1536w, https:\/\/www.ppd.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/access-solutions-video-conference_1818069584_parallax-60x30.jpg 60w' alt='' \/>\t\t<\/div>\n\t\n\t<div class=\"bg-content-block__overlay\">\n\t\t<div class=\"inner alignwide\">\n\t\t\t<div class=\"bg-content-block__body\">\n\t\t\t\t\t\t\t\t<h2 class=\"bg-content-block__title\">Une livraison mondiale associ\u00e9e \u00e0 un contr\u00f4le local <\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bg-content-block__content\"><p><span class=\"TextRun SCXW155568545 BCX0\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW155568545 BCX0\">Il est essentiel de disposer de soutien au niveau local et mondial. Notre approche en mati\u00e8re de ressources offre un soutien sp\u00e9cifique pour assure les livrables <\/span><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW155568545 BCX0\">aux niveaux r\u00e9gional<\/span><span class=\"NormalTextRun SCXW155568545 BCX0\">, national et mondial.<\/span><\/span><span class=\"EOP SCXW155568545 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span class=\"TextRun SCXW52301450 BCX0\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW52301450 BCX0\">Pour optimiser les communications et les interactions, nos employ\u00e9s couvrent tous les fuseaux horaires, offrant ainsi un service transparent 24\u202fheures sur\u202f24 assum\u00e9 par les \u00e9quipes sur place et les \u00e9quipes virtuelles. Cela nous permet de placer nos postes en contact avec les clients dans les m\u00eames fuseaux horaires que vos \u00e9quipes fonctionnelles et cliniques, permettant ainsi \u00e0 l\u2019\u00e9quipe combin\u00e9e de devenir un groupe unifi\u00e9 et consacr\u00e9 qui s\u2019int\u00e8gre \u00e0 votre fonction de gestion des donn\u00e9es.<\/span><\/span><span class=\"EOP SCXW52301450 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<p><span class=\"TextRun SCXW132436500 BCX0\" lang=\"FR-CA\" xml:lang=\"FR-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW132436500 BCX0\">Gr\u00e2ce \u00e0 notre approche \u00e9prouv\u00e9e, nous cr\u00e9ons collectivement des \u00e9quipes performantes, encourageons la mise en commun des connaissances et produisons des interactions positives et productives pendant toute la dur\u00e9e de notre partenariat.<\/span><\/span><span class=\"EOP SCXW132436500 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<div style=\"height:2.5rem\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-left\" style=\"text-transform:none\">Des solutions et une dotation en personnel sur mesure pour r\u00e9pondre au mieux \u00e0 vos besoins&nbsp;<\/h2>\n\n\n\n<div class=\"wp-block-emagine-columns alignfull\"><div id=\"em-layout-id_2701c5-f4\" class=\"em-row-layout-inner em-margin-top--none em-margin-bottom--default em-tablet-margin-top--default em-tablet-margin-bottom--default em-mobile-margin-top--none em-mobile-margin-bottom--none   em-layout-id_2701c5-f4\"><div class=\"em-row-column-wrap em-has-2-columns em-gutter-default em-row-valign-top em-row-layout-equal em-tab-layout-equal em-m-colapse-right-to-left em-mobile-layout-row em-padding-top--default em-padding-bottom--default em-tablet-padding-top--default em-tablet-padding-bottom--default em-mobile-padding-top--default em-mobile-padding-bottom--default alignwide\">\n<div class=\"wp-block-emagine-column emagine-column7092 inner-column-1\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--medium em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--medium em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--medium em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\">\n<h3 class=\"wp-block-heading\">Des mod\u00e8les souples livr\u00e9s par des \u00e9quipes comp\u00e9tentes<\/h3>\n\n\n\n<p>Nous travaillons directement avec vous pour vous fournir le meilleur mod\u00e8le d\u2019externalisation pour vos projets, y compris une combinaison souple de syst\u00e8mes, de processus, de supervision et d\u2019installations. Nous pouvons int\u00e9grer du personnel dans votre effectif ou reprendre l&#8217;activit\u00e9 en interne en utilisant nos innovations et nos technologies. Nos \u00e9quipes de projet, qui font preuve de la souplesse n\u00e9cessaire pour fournir des solutions qui r\u00e9pondent \u00e0 vos besoins uniques, comprennent une combinaison personnalis\u00e9e de postes.&nbsp;<\/p>\n\n\n\n<p>Une \u00e9quipe typique pourrait comprendre un chef de groupe (directeur associ\u00e9\/directeur) qui supervise les processus, les \u00e9ch\u00e9anciers et les contrats, et veille au respect des normes de qualit\u00e9. Un chef de projet de\u202fGDC affecte les ressources, g\u00e8re les budgets et les contrats, \u00e9value le projet aux fins de gestion du risque et des modifications contractuelles. Un chef d\u2019\u00e9quipe de\u202fGDC collabore avec le chef de projet de\u202fGDC pour assurer la responsabilit\u00e9 de toutes les activit\u00e9s et de tous les livrables du projet. Au besoin, on compl\u00e8te l\u2019\u00e9quipe avec plusieurs autres postes.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-emagine-column emagine-column1119 inner-column-2\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--none em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--none em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.ppd.com\/wp-content\/uploads\/2021\/08\/med-comm-shutterstock_701020606.jpg\" alt=\"\" class=\"wp-image-20318\"\/><\/figure>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-emagine-columns alignfull\"><div id=\"em-layout-id_5c35e7-ac\" class=\"em-row-layout-inner em-margin-top--none em-margin-bottom--default em-tablet-margin-top--default em-tablet-margin-bottom--default em-mobile-margin-top--none em-mobile-margin-bottom--none   em-layout-id_5c35e7-ac\"><div class=\"em-row-column-wrap em-has-2-columns em-gutter-default em-row-valign-top em-row-layout-equal em-tab-layout-equal em-m-colapse-left-to-right em-mobile-layout-row em-padding-top--default em-padding-bottom--default em-tablet-padding-top--default em-tablet-padding-bottom--default em-mobile-padding-top--default em-mobile-padding-bottom--default alignwide\">\n<div class=\"wp-block-emagine-column emagine-column2815 inner-column-1\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--medium em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--medium em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--medium em-mobile-padding-left--none\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.ppd.com\/wp-content\/uploads\/2022\/12\/infographic-blog-shutterstock_2059328342-1024x576.jpg\" alt=\"Virtual screen of the future featuring numbers, graphs and the words &quot;clinical trial&quot;\" class=\"wp-image-24429\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-emagine-column emagine-column4108 inner-column-2\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--none em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--none em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\">\n<h3 class=\"wp-block-heading\">Une technologie personnalis\u00e9e pour rationaliser les prestations op\u00e9rationnelles<\/h3>\n\n\n\n<p>Nous travaillons \u00e9galement en \u00e9troite collaboration avec vous pour mettre au point une technologie de collecte de donn\u00e9es et des solutions de traitement sur mesure, afin de r\u00e9pondre \u00e0 vos besoins op\u00e9rationnels en mati\u00e8re de livraison. En utilisant soit vos modes op\u00e9ratoires normalis\u00e9s\u202f(MON) et vos syst\u00e8mes, soit nos MON, les technologies d\u2019interfaces \u00ab\u202fen temps r\u00e9el\u202f\u00bb et de d\u00e9clarations \u00e9lectroniques des r\u00e9sultats par les patients, nous ciblons l\u2019am\u00e9lioration de la vitesse d\u2019acquisition et de l\u2019examen des donn\u00e9es. Nous respectons rigoureusement les proc\u00e9dures li\u00e9es aux op\u00e9rations et \u00e0 la qualit\u00e9, dans le but d\u2019assurer l\u2019int\u00e9grit\u00e9 des donn\u00e9es. En outre, nous poss\u00e9dons une vaste exp\u00e9rience des syst\u00e8mes de\u202fSED, ce qui nous permet de travailler avec le syst\u00e8me de votre choix.&nbsp;<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-emagine-columns alignfull\"><div id=\"em-layout-id_b62c3b-ec\" class=\"em-row-layout-inner em-margin-top--none em-margin-bottom--default em-tablet-margin-top--default em-tablet-margin-bottom--default em-mobile-margin-top--none em-mobile-margin-bottom--default   em-layout-id_b62c3b-ec\"><div class=\"em-row-column-wrap em-has-2-columns em-gutter-default em-row-valign-top em-row-layout-equal em-tab-layout-equal em-m-colapse-right-to-left em-mobile-layout-row em-padding-top--default em-padding-bottom--default em-tablet-padding-top--default em-tablet-padding-bottom--default em-mobile-padding-top--default em-mobile-padding-bottom--default alignwide\">\n<div class=\"wp-block-emagine-column emagine-column8379 inner-column-1\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--medium em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--medium em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--medium em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\">\n<h3 class=\"wp-block-heading\">Un personnel consacr\u00e9 suit une formation sp\u00e9cialis\u00e9e<\/h3>\n\n\n\n<p>Avant le d\u00e9but de notre partenariat, nos gestionnaires de personnel consacr\u00e9 veillent \u00e0 ce que tout le personnel affect\u00e9 re\u00e7oive une formation sur les\u202fMON, les processus et les technologies propres \u00e0 votre entreprise, ainsi qu\u2019une formation sp\u00e9cifique de l\u2019\u00e9tude et notre formation interne \u00e0 l&#8217;entreprise. Notre perfectionnement professionnel et notre culture de l\u2019apprentissage contribuent \u00e9galement \u00e0 faire de l\u2019activit\u00e9 de recherche clinique de\u202fPPD\u2122, une soci\u00e9t\u00e9 de Thermo Fisher Scientific, une entreprise o\u00f9 il fait bon travailler, qui favorise l\u2019engagement et la fid\u00e9lisation des employ\u00e9s de\u202fGDC.&nbsp;<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-emagine-column emagine-column3496 inner-column-2\"><div class=\"em-inside-inner-col em-padding-top--none em-padding-right--none em-padding-bottom--none em-padding-left--none em-tablet-padding-top--none em-tablet-padding-right--none em-tablet-padding-bottom--none em-tablet-padding-left--none em-mobile-padding-top--none em-mobile-padding-right--none em-mobile-padding-bottom--none em-mobile-padding-left--none\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.ppd.com\/wp-content\/uploads\/2023\/07\/patient-centricity-webinar-HPP-shutterstock_2222224091-1024x512.jpg\" alt=\"Black male patient reviews medical records alongside a female Asian nurse in the waiting room of a medical facility\" class=\"wp-image-25971\"\/><\/figure>\n<\/div><\/div>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des solutions et une dotation en personnel sur mesure pour r\u00e9pondre au mieux \u00e0 vos besoins&nbsp;<\/p>\n","protected":false},"author":3,"featured_media":213,"parent":35,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"1","_relevanssi_noindex_reason":"","em_featured_video_id":0,"footnotes":""},"class_list":["post-38","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/pages\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":0,"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/pages\/38\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/pages\/35"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/media\/213"}],"wp:attachment":[{"href":"https:\/\/www.ppd.com\/fr\/wp-json\/wp\/v2\/media?parent=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}